{"id":14963,"date":"2023-03-02T17:42:42","date_gmt":"2023-03-02T17:42:42","guid":{"rendered":"https:\/\/ferrangarreta.net\/boucles-doreille\/"},"modified":"2023-12-04T20:52:32","modified_gmt":"2023-12-04T20:52:32","slug":"boucles-doreille","status":"publish","type":"page","link":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/","title":{"rendered":"Boucles d&rsquo;oreilles"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14963\" class=\"elementor elementor-14963 elementor-995\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8814fdb elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"8814fdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbc38a4\" data-id=\"dbc38a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a98e73f elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"a98e73f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-85eb97b swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"JR7. Bague et boucles d&#039;oreilles. Or jaune, perles de culture et de diamants.\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa1ddf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa1ddf8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fed934\" data-id=\"0fed934\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-483fd3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"483fd3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-686aea5\" data-id=\"686aea5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba5add3 elementor-widget elementor-widget-heading\" data-id=\"ba5add3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bijouterie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4890af3 elementor-widget elementor-widget-heading\" data-id=\"4890af3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Boucles d'oreilles<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-812646e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"812646e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7d57736\" data-id=\"7d57736\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb8c7c6 elementor-widget elementor-widget-text-editor\" data-id=\"cb8c7c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tArt vivant \u00e0 travers les si\u00e8cles, l&rsquo;art des bijoux n\u00e9cessite une grande habilet\u00e9 et combine avec soin les diff\u00e9rentes techniques, y compris la joaillerie, la gravure, le sertissage\net l&rsquo;\u00e9mail. Nos cr\u00e9ations, pi\u00e8ces uniques sont\nle r\u00e9sultat d\u2019une id\u00e9e dans laquelle le d\u00e9sir du client est notre priorit\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83c3675 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"83c3675\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a27d7b\" data-id=\"4a27d7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e3106c elementor-widget elementor-widget-gallery\" data-id=\"5e3106c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:5,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;25&quot;,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;overlay_title&quot;:&quot;title&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR1.-Arracades-dor-blanc-i-aiguamarines-talla-princesa.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR1. Boucles d&#039;oreilles en or blanc et aigues-marines taille princesse.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NTcsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjEuLUFycmFjYWRlcy1kb3ItYmxhbmMtaS1haWd1YW1hcmluZXMtdGFsbGEtcHJpbmNlc2EuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR1.-Arracades-dor-blanc-i-aiguamarines-talla-princesa.jpg\" data-width=\"2371\" data-height=\"1694\" aria-label=\"JR1. Boucles d&#039;oreilles en or blanc et aigues-marines taille princesse.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR1. Boucles d'oreilles en or blanc et aigues-marines taille princesse.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR2.-Arracades-dor-blanc-i-diamants-blaus.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR2. Boucles d&#039;oreilles en or blanc et diamants bleus.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NjAsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjIuLUFycmFjYWRlcy1kb3ItYmxhbmMtaS1kaWFtYW50cy1ibGF1cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR2.-Arracades-dor-blanc-i-diamants-blaus.jpg\" data-width=\"1912\" data-height=\"1409\" aria-label=\"JR2. Boucles d&#039;oreilles en or blanc et diamants bleus.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR2. Boucles d'oreilles en or blanc et diamants bleus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR3.-Arracades-dor-blanc-perles-cultivades-i-diamants-blaus.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR3. Boucles d&#039;oreilles en or blanc, perles de culture et diamants bleus.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NjMsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjMuLUFycmFjYWRlcy1kb3ItYmxhbmMtcGVybGVzLWN1bHRpdmFkZXMtaS1kaWFtYW50cy1ibGF1cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR3.-Arracades-dor-blanc-perles-cultivades-i-diamants-blaus.jpg\" data-width=\"728\" data-height=\"832\" aria-label=\"JR3. Boucles d&#039;oreilles en or blanc, perles de culture et diamants bleus.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR3. Boucles d'oreilles en or blanc, perles de culture et diamants bleus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR4.-Arracades-dor-groc.-Diamants-esmeraldes-robins-peridot-i-espinela.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR4. Boucles d&#039;oreilles en or jaune. Diamants, \u00e9meraudes, rubis, p\u00e9ridot et spinelle.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NjYsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjQuLUFycmFjYWRlcy1kb3ItZ3JvYy4tRGlhbWFudHMtZXNtZXJhbGRlcy1yb2JpbnMtcGVyaWRvdC1pLWVzcGluZWxhLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR4.-Arracades-dor-groc.-Diamants-esmeraldes-robins-peridot-i-espinela.jpg\" data-width=\"749\" data-height=\"583\" aria-label=\"JR4. Boucles d&#039;oreilles en or jaune. Diamants, \u00e9meraudes, rubis, p\u00e9ridot et spinelle.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR4. Boucles d'oreilles en or jaune. Diamants, \u00e9meraudes, rubis, p\u00e9ridot et spinelle.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR5.-Arracades-dor-groc-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR5. Boucles d&#039;oreilles en or jaune et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NjksInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjUuLUFycmFjYWRlcy1kb3ItZ3JvYy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR5.-Arracades-dor-groc-i-diamants.jpg\" data-width=\"624\" data-height=\"624\" aria-label=\"JR5. Boucles d&#039;oreilles en or jaune et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR5. Boucles d'oreilles en or jaune et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR6.-Arracades-dor-blanc-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR6. Boucles d&#039;oreilles en or blanc, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NzIsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjYuLUFycmFjYWRlcy1kb3ItYmxhbmMtcGVybGVzLWN1bHRpdmFkZXMtaS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR6.-Arracades-dor-blanc-perles-cultivades-i-diamants.jpg\" data-width=\"2060\" data-height=\"1545\" aria-label=\"JR6. Boucles d&#039;oreilles en or blanc, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR6. Boucles d'oreilles en or blanc, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR7.-Anell-i-arracades.-Or-groc-perles-cultivades-i-diamants-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR7. Bague et boucles d&#039;oreilles. Or jaune, perles de culture et de diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NzUsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjcuLUFuZWxsLWktYXJyYWNhZGVzLi1Pci1ncm9jLXBlcmxlcy1jdWx0aXZhZGVzLWktZGlhbWFudHMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR7.-Anell-i-arracades.-Or-groc-perles-cultivades-i-diamants-scaled.jpg\" data-width=\"2560\" data-height=\"2048\" aria-label=\"JR7. Bague et boucles d&#039;oreilles. Or jaune, perles de culture et de diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR7. Bague et boucles d'oreilles. Or jaune, perles de culture et de diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR8.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR8. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5NzgsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjguLUFycmFjYWRlcy1kb3ItZ3JvYy1wZXJsZXMtY3VsdGl2YWRlcy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR8.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-width=\"2287\" data-height=\"1715\" aria-label=\"JR8. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR8. Boucles d'oreilles en or jaune, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR9.-Fermall-i-arracades.-Or-groc-esmalt-al-foc-en-vitrall-i-robins-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR9. Broche et boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5ODEsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjkuLUZlcm1hbGwtaS1hcnJhY2FkZXMuLU9yLWdyb2MtZXNtYWx0LWFsLWZvYy1lbi12aXRyYWxsLWktcm9iaW5zLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR9.-Fermall-i-arracades.-Or-groc-esmalt-al-foc-en-vitrall-i-robins-scaled.jpg\" data-width=\"2560\" data-height=\"1920\" aria-label=\"JR9. Broche et boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR9. Broche et boucles d'oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR10.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR10. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5ODQsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjEwLi1BcnJhY2FkZXMtZG9yLWdyb2MtcGVybGVzLWN1bHRpdmFkZXMtaS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR10.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-width=\"2500\" data-height=\"2024\" aria-label=\"JR10. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR10. Boucles d'oreilles en or jaune, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR11.-Penjoll-i-arracades-dor-groc-turquesa-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR11. Pendentif et boucles d&#039;oreilles en or jaune, turquoise et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5ODcsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjExLi1QZW5qb2xsLWktYXJyYWNhZGVzLWRvci1ncm9jLXR1cnF1ZXNhLWktZGlhbWFudHMuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR11.-Penjoll-i-arracades-dor-groc-turquesa-i-diamants.jpg\" data-width=\"1912\" data-height=\"1912\" aria-label=\"JR10. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR11. Pendentif et boucles d'oreilles en or jaune, turquoise et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR12.-Arracades-dor-groc-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR12. Boucles d&#039;oreilles en or jaune et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5OTAsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjEyLi1BcnJhY2FkZXMtZG9yLWdyb2MtaS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR12.-Arracades-dor-groc-i-diamants.jpg\" data-width=\"586\" data-height=\"586\" aria-label=\"JR12. Boucles d&#039;oreilles en or jaune et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR12. Boucles d'oreilles en or jaune et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR13.-Fermall-i-arracades.-Or-groc-esmalts-al-foc-en-vitrall-i-robins-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR13. Broche et boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5OTMsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjEzLi1GZXJtYWxsLWktYXJyYWNhZGVzLi1Pci1ncm9jLWVzbWFsdHMtYWwtZm9jLWVuLXZpdHJhbGwtaS1yb2JpbnMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR13.-Fermall-i-arracades.-Or-groc-esmalts-al-foc-en-vitrall-i-robins-scaled.jpg\" data-width=\"2560\" data-height=\"1920\" aria-label=\"JR13. Broche et boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR13. Broche et boucles d'oreilles en or jaune, \u00e9maux au feu en vitrail et rubis.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR14.-Arracades-de-plata-esmalts-al-foc-en-vitral-topazis-blaus-i-nacre-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR14. Boucles d&#039;oreilles en argent, \u00e9maux au feu en vitrail, topazes bleues et nacre.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5OTYsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE0Li1BcnJhY2FkZXMtZGUtcGxhdGEtZXNtYWx0cy1hbC1mb2MtZW4tdml0cmFsLXRvcGF6aXMtYmxhdXMtaS1uYWNyZS1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR14.-Arracades-de-plata-esmalts-al-foc-en-vitral-topazis-blaus-i-nacre-scaled.jpg\" data-width=\"2560\" data-height=\"1991\" aria-label=\"JR14. Boucles d&#039;oreilles en argent, \u00e9maux au feu en vitrail, topazes bleues et nacre.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR14. Boucles d'oreilles en argent, \u00e9maux au feu en vitrail, topazes bleues et nacre.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR15.-Arracades-dor-blanc-i-diamants-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR15. Boucles d&#039;oreilles en or blanc et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5OTksInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE1Li1BcnJhY2FkZXMtZG9yLWJsYW5jLWktZGlhbWFudHMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR15.-Arracades-dor-blanc-i-diamants-scaled.jpg\" data-width=\"2011\" data-height=\"2560\" aria-label=\"JR15. Boucles d&#039;oreilles en or blanc et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR15. Boucles d'oreilles en or blanc et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR16.-Arracades-dor-groc-esmalts-al-foc-en-vitrall-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR16. Boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMDIsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE2Li1BcnJhY2FkZXMtZG9yLWdyb2MtZXNtYWx0cy1hbC1mb2MtZW4tdml0cmFsbC1wZXJsZXMtY3VsdGl2YWRlcy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR16.-Arracades-dor-groc-esmalts-al-foc-en-vitrall-perles-cultivades-i-diamants.jpg\" data-width=\"2046\" data-height=\"2046\" aria-label=\"JR16. Boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR16. Boucles d'oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR17.-Arracades-dor-blanc-peridots-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR17. Boucles d&#039;oreilles en or blanc, p\u00e9ridots et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMDUsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE3Li1BcnJhY2FkZXMtZG9yLWJsYW5jLXBlcmlkb3RzLWktZGlhbWFudHMuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR17.-Arracades-dor-blanc-peridots-i-diamants.jpg\" data-width=\"2202\" data-height=\"1712\" aria-label=\"JR17. Boucles d&#039;oreilles en or blanc, p\u00e9ridots et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR17. Boucles d'oreilles en or blanc, p\u00e9ridots et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR18.-Arracades-dor-groc-esmeraldes-robins-i-safirs-blaus.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR18. Boucles d&#039;oreilles en or jaune, \u00e9meraudes, rubis et saphirs bleus.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMDgsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE4Li1BcnJhY2FkZXMtZG9yLWdyb2MtZXNtZXJhbGRlcy1yb2JpbnMtaS1zYWZpcnMtYmxhdXMuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR18.-Arracades-dor-groc-esmeraldes-robins-i-safirs-blaus.jpg\" data-width=\"2491\" data-height=\"1557\" aria-label=\"JR18. Boucles d&#039;oreilles en or jaune, \u00e9meraudes, rubis et saphirs bleus.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR18. Boucles d'oreilles en or jaune, \u00e9meraudes, rubis et saphirs bleus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR19.-Arracades-i-penjoll.-Or-groc-esmeraldes-safirs-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR19. Boucles d&#039;oreilles en or blanc, \u00e9maux au feu en vitrail et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMTEsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjE5Li1BcnJhY2FkZXMtaS1wZW5qb2xsLi1Pci1ncm9jLWVzbWVyYWxkZXMtc2FmaXJzLWktZGlhbWFudHMuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR19.-Arracades-i-penjoll.-Or-groc-esmeraldes-safirs-i-diamants.jpg\" data-width=\"1741\" data-height=\"1323\" aria-label=\"JR19. Boucles d&#039;oreilles en or blanc, \u00e9maux au feu en vitrail et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR19. Boucles d'oreilles en or blanc, \u00e9maux au feu en vitrail et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR20.-Arracades-lor-groc-esmalts-al-foc-en-vitrall-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR20. Boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMTQsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjIwLi1BcnJhY2FkZXMtbG9yLWdyb2MtZXNtYWx0cy1hbC1mb2MtZW4tdml0cmFsbC1wZXJsZXMtY3VsdGl2YWRlcy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR20.-Arracades-lor-groc-esmalts-al-foc-en-vitrall-perles-cultivades-i-diamants.jpg\" data-width=\"2088\" data-height=\"1740\" aria-label=\"JR20. Boucles d&#039;oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR20. Boucles d'oreilles en or jaune, \u00e9maux au feu en vitrail, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR21.-Arracades-dor-groc-perles-cultivades-i-diamants-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR21. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMTcsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjIxLi1BcnJhY2FkZXMtZG9yLWdyb2MtcGVybGVzLWN1bHRpdmFkZXMtaS1kaWFtYW50cy1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR21.-Arracades-dor-groc-perles-cultivades-i-diamants-scaled.jpg\" data-width=\"2560\" data-height=\"1920\" aria-label=\"JR21. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR21. Boucles d'oreilles en or jaune, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR22.-Arracades-i-penjoll.-Or-groc-i-quarts-citri.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR22. Boucles d&#039;oreilles et pendentif. Or jaune et quarts citrine.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMjAsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjIyLi1BcnJhY2FkZXMtaS1wZW5qb2xsLi1Pci1ncm9jLWktcXVhcnRzLWNpdHJpLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR22.-Arracades-i-penjoll.-Or-groc-i-quarts-citri.jpg\" data-width=\"2295\" data-height=\"1785\" aria-label=\"JR22. Boucles d&#039;oreilles et pendentif. Or jaune et quarts citrine.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR22. Boucles d'oreilles et pendentif. Or jaune et quarts citrine.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR23.-Arracades-i-anell.-Or-groc-i-aiguamarines-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR23. Boucles d&#039;oreilles et bague. Or jaune et aigues-marines.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMjMsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjIzLi1BcnJhY2FkZXMtaS1hbmVsbC4tT3ItZ3JvYy1pLWFpZ3VhbWFyaW5lcy1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR23.-Arracades-i-anell.-Or-groc-i-aiguamarines-scaled.jpg\" data-width=\"1920\" data-height=\"2560\" aria-label=\"JR22. Boucles d&#039;oreilles et pendentif. Or jaune et quarts citrine.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR23. Boucles d'oreilles et bague. Or jaune et aigues-marines.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR24.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR24. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMjYsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI0Li1BcnJhY2FkZXMtZG9yLWdyb2MtcGVybGVzLWN1bHRpdmFkZXMtaS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR24.-Arracades-dor-groc-perles-cultivades-i-diamants.jpg\" data-width=\"1603\" data-height=\"1048\" aria-label=\"JR24. Boucles d&#039;oreilles en or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR24. Boucles d'oreilles en or jaune, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR25.-Anell-i-arracades.-Or-groc-perles-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR25. Bague et boucles d&#039;oreilles. Or jaune, perles de culture et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMjksInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI1Li1BbmVsbC1pLWFycmFjYWRlcy4tT3ItZ3JvYy1wZXJsZXMtY3VsdGl2YWRlcy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR25.-Anell-i-arracades.-Or-groc-perles-cultivades-i-diamants.jpg\" data-width=\"800\" data-height=\"1168\" aria-label=\"JR25. Bague et boucles d&#039;oreilles. Or jaune, perles de culture et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR25. Bague et boucles d'oreilles. Or jaune, perles de culture et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR26.-Arracades-i-anell.-Or-groc.-esmeralda-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR26. Boucles d&#039;oreilles et bague. Or jaune, \u00e9meraude et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMzIsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI2Li1BcnJhY2FkZXMtaS1hbmVsbC4tT3ItZ3JvYy4tZXNtZXJhbGRhLWktZGlhbWFudHMuanBnIiwic2xpZGVzaG93IjoiNWUzMTA2YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR26.-Arracades-i-anell.-Or-groc.-esmeralda-i-diamants.jpg\" data-width=\"2131\" data-height=\"1332\" aria-label=\"JR26. Boucles d&#039;oreilles et bague. Or jaune, \u00e9meraude et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR26. Boucles d'oreilles et bague. Or jaune, \u00e9meraude et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR27.-Arracades-dor-blanc-robins-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR27. Boucles d&#039;oreilles en or blanc, rubis et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMzUsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI3Li1BcnJhY2FkZXMtZG9yLWJsYW5jLXJvYmlucy1pLWRpYW1hbnRzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR27.-Arracades-dor-blanc-robins-i-diamants.jpg\" data-width=\"1927\" data-height=\"1927\" aria-label=\"JR27. Boucles d&#039;oreilles en or blanc, rubis et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR27. Boucles d'oreilles en or blanc, rubis et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR28.-Arracades-dor-blanc-robins-i-diamants-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR28. Boucles d&#039;oreilles en or blanc, rubis et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwMzgsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI4Li1BcnJhY2FkZXMtZG9yLWJsYW5jLXJvYmlucy1pLWRpYW1hbnRzLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR28.-Arracades-dor-blanc-robins-i-diamants-scaled.jpg\" data-width=\"2560\" data-height=\"1280\" aria-label=\"JR28. Boucles d&#039;oreilles en or blanc, rubis et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR28. Boucles d'oreilles en or blanc, rubis et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR29.-Arracades-dor-blanc-perles-cultivades-i-pave-de-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR29. Boucles d&#039;oreilles en or blanc, perles de culture et pav\u00e9 diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwNDEsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjI5Li1BcnJhY2FkZXMtZG9yLWJsYW5jLXBlcmxlcy1jdWx0aXZhZGVzLWktcGF2ZS1kZS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR29.-Arracades-dor-blanc-perles-cultivades-i-pave-de-diamants.jpg\" data-width=\"1911\" data-height=\"1911\" aria-label=\"JR29. Boucles d&#039;oreilles en or blanc, perles de culture et pav\u00e9 diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR29. Boucles d'oreilles en or blanc, perles de culture et pav\u00e9 diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR30.-Arracades-dor-blanc-perles-mabe-cultivades-i-diamants.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR30. Boucles d&#039;oreilles en or blanc, perles de culture mabe et diamants.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwNDQsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjMwLi1BcnJhY2FkZXMtZG9yLWJsYW5jLXBlcmxlcy1tYWJlLWN1bHRpdmFkZXMtaS1kaWFtYW50cy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR30.-Arracades-dor-blanc-perles-mabe-cultivades-i-diamants.jpg\" data-width=\"2484\" data-height=\"2160\" aria-label=\"JR30. Boucles d&#039;oreilles en or blanc, perles de culture mabe et diamants.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR30. Boucles d'oreilles en or blanc, perles de culture mabe et diamants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR31.-Penjoll-i-arracades.-Or-groc-i-ametistes.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR31. Pendentif et boucles d&#039;oreilles. Or jaune et am\u00e9thystes.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwNDcsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjMxLi1QZW5qb2xsLWktYXJyYWNhZGVzLi1Pci1ncm9jLWktYW1ldGlzdGVzLmpwZyIsInNsaWRlc2hvdyI6IjVlMzEwNmMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR31.-Penjoll-i-arracades.-Or-groc-i-ametistes.jpg\" data-width=\"1822\" data-height=\"1518\" aria-label=\"JR31. Pendentif et boucles d&#039;oreilles. Or jaune et am\u00e9thystes.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR31. Pendentif et boucles d'oreilles. Or jaune et am\u00e9thystes.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR32.-Arracades-de-plata-robins-esmeraldes-i-swarovskis-blancs.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e3106c\" data-elementor-lightbox-title=\"JR32. Boucles d&#039;oreilles en argent, rubis, \u00e9meraudes et zircons.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMwNTAsInVybCI6Imh0dHBzOlwvXC93d3cuZmVycmFuZ2FycmV0YS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9KUjMyLi1BcnJhY2FkZXMtZGUtcGxhdGEtcm9iaW5zLWVzbWVyYWxkZXMtaS1zd2Fyb3Zza2lzLWJsYW5jcy5qcGciLCJzbGlkZXNob3ciOiI1ZTMxMDZjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/04\/JR32.-Arracades-de-plata-robins-esmeraldes-i-swarovskis-blancs.jpg\" data-width=\"1336\" data-height=\"1162\" aria-label=\"JR32. Boucles d&#039;oreilles en argent, rubis, \u00e9meraudes et zircons.\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tJR32. Boucles d'oreilles en argent, rubis, \u00e9meraudes et zircons.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bijouterie Boucles d&rsquo;oreilles Art vivant \u00e0 travers les si\u00e8cles, l&rsquo;art des bijoux n\u00e9cessite une grande habilet\u00e9 et combine avec soin les diff\u00e9rentes techniques, y compris la joaillerie, la gravure, le sertissage et l&rsquo;\u00e9mail. Nos cr\u00e9ations, pi\u00e8ces uniques sont le r\u00e9sultat d\u2019une id\u00e9e dans laquelle le d\u00e9sir du client est notre priorit\u00e9. JR1. Arracades d\u2019or blanc [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14963","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boucles d&#039;oreilles - Ferran Garreta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boucles d&#039;oreilles - Ferran Garreta\" \/>\n<meta property=\"og:description\" content=\"Bijouterie Boucles d&rsquo;oreilles Art vivant \u00e0 travers les si\u00e8cles, l&rsquo;art des bijoux n\u00e9cessite une grande habilet\u00e9 et combine avec soin les diff\u00e9rentes techniques, y compris la joaillerie, la gravure, le sertissage et l&rsquo;\u00e9mail. Nos cr\u00e9ations, pi\u00e8ces uniques sont le r\u00e9sultat d\u2019une id\u00e9e dans laquelle le d\u00e9sir du client est notre priorit\u00e9. JR1. Arracades d\u2019or blanc [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferran Garreta\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T20:52:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/boucles-doreille\\\/\",\"url\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/boucles-doreille\\\/\",\"name\":\"Boucles d'oreilles - Ferran Garreta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-03-02T17:42:42+00:00\",\"dateModified\":\"2023-12-04T20:52:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/boucles-doreille\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/boucles-doreille\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/boucles-doreille\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/principale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boucles d&#8217;oreilles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/\",\"name\":\"Ferran Garreta\",\"description\":\"Empresa familiar ubicada a la ciutat de Vic (Barcelona), dedicada al treball de l\u2019aram, el llaut\u00f3, la plata i l\u2019or, de forma art\u00edstica i manual.Ferran Garreta \u00e9s una empresa familiar ubicada a la ciutat de Vic (Barcelona), dedicada al treball de l\u2019aram, el llaut\u00f3, la plata i l\u2019or, de forma art\u00edstica i manual.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#organization\",\"name\":\"Ferran Garreta\",\"url\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ferrangarreta.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ferran-garreta-logo-w.png\",\"contentUrl\":\"https:\\\/\\\/www.ferrangarreta.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ferran-garreta-logo-w.png\",\"width\":1003,\"height\":184,\"caption\":\"Ferran Garreta\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ferrangarreta.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boucles d'oreilles - Ferran Garreta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/","og_locale":"fr_FR","og_type":"article","og_title":"Boucles d'oreilles - Ferran Garreta","og_description":"Bijouterie Boucles d&rsquo;oreilles Art vivant \u00e0 travers les si\u00e8cles, l&rsquo;art des bijoux n\u00e9cessite une grande habilet\u00e9 et combine avec soin les diff\u00e9rentes techniques, y compris la joaillerie, la gravure, le sertissage et l&rsquo;\u00e9mail. Nos cr\u00e9ations, pi\u00e8ces uniques sont le r\u00e9sultat d\u2019une id\u00e9e dans laquelle le d\u00e9sir du client est notre priorit\u00e9. JR1. Arracades d\u2019or blanc [&hellip;]","og_url":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/","og_site_name":"Ferran Garreta","article_modified_time":"2023-12-04T20:52:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/","url":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/","name":"Boucles d'oreilles - Ferran Garreta","isPartOf":{"@id":"https:\/\/www.ferrangarreta.com\/fr\/#website"},"datePublished":"2023-03-02T17:42:42+00:00","dateModified":"2023-12-04T20:52:32+00:00","breadcrumb":{"@id":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ferrangarreta.com\/fr\/boucles-doreille\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.ferrangarreta.com\/fr\/principale\/"},{"@type":"ListItem","position":2,"name":"Boucles d&#8217;oreilles"}]},{"@type":"WebSite","@id":"https:\/\/www.ferrangarreta.com\/fr\/#website","url":"https:\/\/www.ferrangarreta.com\/fr\/","name":"Ferran Garreta","description":"Empresa familiar ubicada a la ciutat de Vic (Barcelona), dedicada al treball de l\u2019aram, el llaut\u00f3, la plata i l\u2019or, de forma art\u00edstica i manual.Ferran Garreta \u00e9s una empresa familiar ubicada a la ciutat de Vic (Barcelona), dedicada al treball de l\u2019aram, el llaut\u00f3, la plata i l\u2019or, de forma art\u00edstica i manual.","publisher":{"@id":"https:\/\/www.ferrangarreta.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ferrangarreta.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ferrangarreta.com\/fr\/#organization","name":"Ferran Garreta","url":"https:\/\/www.ferrangarreta.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ferrangarreta.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/02\/ferran-garreta-logo-w.png","contentUrl":"https:\/\/www.ferrangarreta.com\/wp-content\/uploads\/2023\/02\/ferran-garreta-logo-w.png","width":1003,"height":184,"caption":"Ferran Garreta"},"image":{"@id":"https:\/\/www.ferrangarreta.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/pages\/14963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/comments?post=14963"}],"version-history":[{"count":5,"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/pages\/14963\/revisions"}],"predecessor-version":[{"id":16759,"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/pages\/14963\/revisions\/16759"}],"wp:attachment":[{"href":"https:\/\/www.ferrangarreta.com\/fr\/wp-json\/wp\/v2\/media?parent=14963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}